{"id":633,"date":"2017-01-11T17:42:38","date_gmt":"2017-01-11T16:42:38","guid":{"rendered":"http:\/\/urban-gardening-blog.de\/Blog\/?p=633"},"modified":"2017-01-11T17:42:38","modified_gmt":"2017-01-11T16:42:38","slug":"bananenpflanze","status":"publish","type":"post","link":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/","title":{"rendered":"Meinen Bananenpflanze lebt wieder!"},"content":{"rendered":"<p>Heute bin ich richtig gl\u00fccklich und zufrieden mit mir &#x1f60a; &#8211; warum? Meine Bananenpflanze bekommt gerade ihr 2. neues Blatt und ihr scheint es wieder gut zu gehen.<\/p>\n<p><div id=\"attachment_638\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-638\" class=\"size-medium wp-image-638\" src=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-300x300.jpg 300w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-150x150.jpg 150w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-768x768.jpg 768w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-638\" class=\"wp-caption-text\">Das 1. neue Blatt vor 1 Woche<\/p><\/div><div id=\"attachment_636\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-636\" class=\"size-medium wp-image-636\" src=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt2-e1484152345363-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt2-e1484152345363-300x300.jpg 300w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt2-e1484152345363-150x150.jpg 150w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt2-e1484152345363-768x768.jpg 768w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt2-e1484152345363-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-636\" class=\"wp-caption-text\">Blatt 2 &#8211; noch eingerollt<\/p><\/div><\/p>\n<p>Warum mich das so gl\u00fccklich macht? Dazu muss ich erstmal ein paar Monate zur\u00fcckgehen:<br \/> Im Herbst hab ich mich in eine Bananenpflanze verliebt: die Fotos, die Beschreibung &#8211; ich musste sie einfach haben! Und in der Kurzbeschreibung des H\u00e4ndlers stand dass sie pflegeleicht w\u00e4re. Also habe ich sie gekauft und leider vers\u00e4umt mich vorher genauer \u00fcber die Anspr\u00fcche der Bananenpflanze kundig zu machen. Die gro\u00dfe Entt\u00e4uschung kam ein paar Wochen sp\u00e4ter: sie sah ziemlich krank aus mit ihren h\u00e4ngenden und braunen Bl\u00e4ttern &#x1f629;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-635 alignnone\" src=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_braun-e1484151877787-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_braun-e1484151877787-225x300.jpg 225w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_braun-e1484151877787-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><br \/> Also ran an den Laptop um nachzulesen was ich falsch gemacht hatte und wie ich die Pflanze wieder in vollem Glanz erstrahlen lassen kann. Die Bananenpflanze (Musa) kommt urspr\u00fcnglich aus tropischen und subtropischen Regionen Asiens und will dementsprechend ein warme und feuchte Umgebung. Nun ja, das hatte sie bei mir wohl eher nicht gehabt, die Liste meiner Fehler war also leider mal wieder lang:<br \/> &#8211; zu schattiger Standort, denn ich hatte sie ins Bad, ca. 2m vom Fenster entfernt platziert<br \/> &#8211; zu geringe Luftfeuchte (sie sollte mind. 50% betragen) &#8211; und nat\u00fcrlich nicht extra mit Wasser bespr\u00fcht<br \/> &#8211; beim Umpflanzen keine Drainage in den Topf gegeben. So dass es bei meinem leider (zum Teil) recht unregelm\u00e4\u00dfigen Gie\u00dfrhythmus manchmal zu Staun\u00e4sse kam, welche die Bananenpflanze gar nicht mag. Allerdings genauso wenig Trockenheit, was ich ihr zwischendurch ebenso zugemutet habe<br \/> &#8211; und zu guter Letzt: ich hatte sie auch nicht ged\u00fcngt und das sollte doch regelm\u00e4\u00dfig erfolgen. Die Empfehlung liegt meist bei 1mal im Monat im Winter und 1mal\/Woche im Sommer.<\/p>\n<p> Also, theoretisch wusste ich nun was zu tun war. Nun musste ich es &#8222;nur&#8220; noch umsetzen. Mitte Dezember habe ich die Bananenpflanze ins Wohnzimmer in die N\u00e4he eines bodentiefes Fensters umgestellt und ged\u00fcngt. Au\u00dferdem habe ich auf regelm\u00e4\u00dfiges Gie\u00dfen (nicht zu viel und nicht zu wenig &#8211; die richtige Menge hatte ich zum Gl\u00fcck schnell raus) geachtet. Zudem habe ich die Pflanze alle 2 Tage mit kalkarmem Wasser bespr\u00fcht.<br \/> Die Standort musste ich nochmal etwas \u00e4ndern (an die gegen\u00fcberliegende, ebenso helle Fensterfront), damit die Bananenpflanze nicht regelm\u00e4\u00dfig die Zugluft von der Balkont\u00fcr abbekam. Zugluft mag sie n\u00e4mlich auch nicht gerne.<\/p>\n<p> Jetzt, nach ca. 1 Monat guter Pflege, sieht sie schon viel besser aus und hat 2 sch\u00f6ne neue Bl\u00e4tter &#8211; die M\u00fche hat sich also auf jeden Fall gelohnt!<\/p>\n<p> Im Sommer werde ich f\u00fcr sie sicher ein sonniges und gesch\u00fctztes Pl\u00e4tzchen auf meiner Dachterrasse suchen.<br \/> Au\u00dferdem werde ich (hofffentlich &#x1f609;) den Ratschlag sie h\u00e4ufig umzutopfen beherzigen. Und vielleicht gibt es ja dann irgendwann wirklich &#8211; so wie auf dem Foto &#8211; rosa Minibanananen. Davon werde ich dann auf jeden Fall auch berichten.<br \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-637 alignnone\" src=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Etikett-e1484152597687-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Etikett-e1484152597687-225x300.jpg 225w, https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Etikett-e1484152597687-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>Und noch eine Erfahrung nehme ich auf jeden Fall mit: auch wenn die Beschreibung beim Verk\u00e4ufer super-einfache Pflege verspricht, so werde ich mich dennoch immer vorher genau \u00fcber die Anspr\u00fcche\u00a0 der jeweiligen Pflanze\u00a0informieren um \u00e4hnliches zu vermeiden!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute bin ich richtig gl\u00fccklich und zufrieden mit mir &#x1f60a; &#8211; warum? Meine Bananenpflanze bekommt gerade ihr 2. neues Blatt und ihr scheint es wieder gut zu gehen. Warum mich das so gl\u00fccklich macht? Dazu muss ich erstmal ein paar Monate zur\u00fcckgehen: Im Herbst hab ich mich in eine Bananenpflanze verliebt: die Fotos, die Beschreibung <a class=\"continue\" href=\"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/\">[Continue]<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_wp_rev_ctl_limit":""},"categories":[1],"tags":[],"class_list":["post-633","post","type-post","status-publish","format-standard","hentry","category-mblog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Meinen Bananenpflanze lebt wieder! - Nettes Stadtgarten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meinen Bananenpflanze lebt wieder!\" \/>\n<meta property=\"og:description\" content=\"Heute bin ich richtig gl\u00fccklich und zufrieden mit mir &#x1f60a; &#8211; warum? Meine Bananenpflanze bekommt gerade ihr 2. neues Blatt und ihr scheint es wieder gut zu gehen. Warum mich das so gl\u00fccklich macht? Dazu muss ich erstmal ein paar Monate zur\u00fcckgehen: Im Herbst hab ich mich in eine Bananenpflanze verliebt: die Fotos, die Beschreibung [Continue]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/\" \/>\n<meta property=\"og:site_name\" content=\"Nettes Stadtgarten\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-11T16:42:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-300x300.jpg\" \/>\n<meta name=\"author\" content=\"Nette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nette\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/\"},\"author\":{\"name\":\"Nette\",\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/#\\\/schema\\\/person\\\/c13187a6abcdab35fb6cc9632cb49b56\"},\"headline\":\"Meinen Bananenpflanze lebt wieder!\",\"datePublished\":\"2017-01-11T16:42:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/#\\\/schema\\\/person\\\/c13187a6abcdab35fb6cc9632cb49b56\"},\"image\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Banane_Blatt1-e1484152421328-300x300.jpg\",\"articleSection\":[\"Mein Blog\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/\",\"url\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/\",\"name\":\"Meinen Bananenpflanze lebt wieder! - Nettes Stadtgarten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Banane_Blatt1-e1484152421328-300x300.jpg\",\"datePublished\":\"2017-01-11T16:42:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Banane_Blatt1-e1484152421328.jpg\",\"contentUrl\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Banane_Blatt1-e1484152421328.jpg\",\"width\":3024,\"height\":3024,\"caption\":\"Das 1. neue Blatt vor 1 Woche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/bananenpflanze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meinen Bananenpflanze lebt wieder!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/\",\"name\":\"Nettes Stadtgarten\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/#\\\/schema\\\/person\\\/c13187a6abcdab35fb6cc9632cb49b56\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/#\\\/schema\\\/person\\\/c13187a6abcdab35fb6cc9632cb49b56\",\"name\":\"Nette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-NSG_Logo_Neu.png\",\"url\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-NSG_Logo_Neu.png\",\"contentUrl\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-NSG_Logo_Neu.png\",\"width\":512,\"height\":512,\"caption\":\"Nette\"},\"logo\":{\"@id\":\"https:\\\/\\\/urban-gardening-blog.de\\\/Blog\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-NSG_Logo_Neu.png\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Meinen Bananenpflanze lebt wieder! - Nettes Stadtgarten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/","og_locale":"de_DE","og_type":"article","og_title":"Meinen Bananenpflanze lebt wieder!","og_description":"Heute bin ich richtig gl\u00fccklich und zufrieden mit mir &#x1f60a; &#8211; warum? Meine Bananenpflanze bekommt gerade ihr 2. neues Blatt und ihr scheint es wieder gut zu gehen. Warum mich das so gl\u00fccklich macht? Dazu muss ich erstmal ein paar Monate zur\u00fcckgehen: Im Herbst hab ich mich in eine Bananenpflanze verliebt: die Fotos, die Beschreibung [Continue]","og_url":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/","og_site_name":"Nettes Stadtgarten","article_published_time":"2017-01-11T16:42:38+00:00","og_image":[{"url":"http:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-300x300.jpg","type":"","width":"","height":""}],"author":"Nette","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Nette","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#article","isPartOf":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/"},"author":{"name":"Nette","@id":"https:\/\/urban-gardening-blog.de\/Blog\/#\/schema\/person\/c13187a6abcdab35fb6cc9632cb49b56"},"headline":"Meinen Bananenpflanze lebt wieder!","datePublished":"2017-01-11T16:42:38+00:00","mainEntityOfPage":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/#\/schema\/person\/c13187a6abcdab35fb6cc9632cb49b56"},"image":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#primaryimage"},"thumbnailUrl":"http:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-300x300.jpg","articleSection":["Mein Blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/","url":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/","name":"Meinen Bananenpflanze lebt wieder! - Nettes Stadtgarten","isPartOf":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#primaryimage"},"image":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#primaryimage"},"thumbnailUrl":"http:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328-300x300.jpg","datePublished":"2017-01-11T16:42:38+00:00","breadcrumb":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#primaryimage","url":"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328.jpg","contentUrl":"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2017\/01\/Banane_Blatt1-e1484152421328.jpg","width":3024,"height":3024,"caption":"Das 1. neue Blatt vor 1 Woche"},{"@type":"BreadcrumbList","@id":"https:\/\/urban-gardening-blog.de\/Blog\/bananenpflanze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/urban-gardening-blog.de\/Blog\/"},{"@type":"ListItem","position":2,"name":"Meinen Bananenpflanze lebt wieder!"}]},{"@type":"WebSite","@id":"https:\/\/urban-gardening-blog.de\/Blog\/#website","url":"https:\/\/urban-gardening-blog.de\/Blog\/","name":"Nettes Stadtgarten","description":"","publisher":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/#\/schema\/person\/c13187a6abcdab35fb6cc9632cb49b56"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/urban-gardening-blog.de\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/urban-gardening-blog.de\/Blog\/#\/schema\/person\/c13187a6abcdab35fb6cc9632cb49b56","name":"Nette","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2025\/01\/cropped-NSG_Logo_Neu.png","url":"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2025\/01\/cropped-NSG_Logo_Neu.png","contentUrl":"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2025\/01\/cropped-NSG_Logo_Neu.png","width":512,"height":512,"caption":"Nette"},"logo":{"@id":"https:\/\/urban-gardening-blog.de\/Blog\/wp-content\/uploads\/2025\/01\/cropped-NSG_Logo_Neu.png"}}]}},"modified_by":"Nette","_links":{"self":[{"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/posts\/633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/comments?post=633"}],"version-history":[{"count":4,"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/posts\/633\/revisions"}],"predecessor-version":[{"id":642,"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/posts\/633\/revisions\/642"}],"wp:attachment":[{"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/media?parent=633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/categories?post=633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urban-gardening-blog.de\/Blog\/wp-json\/wp\/v2\/tags?post=633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}